{"id":1745,"date":"2013-10-16T17:35:26","date_gmt":"2013-10-16T07:35:26","guid":{"rendered":"http:\/\/nextrachermside.com.au\/pages\/?p=1745"},"modified":"2013-10-16T17:35:26","modified_gmt":"2013-10-16T07:35:26","slug":"rspca-imprint-magazine","status":"publish","type":"post","link":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/","title":{"rendered":"RSPCA &#8216;Imprint&#8217; Magazine"},"content":{"rendered":"<p>Our store was recently recognised as RSPCA Queensland&#8217;s top fundraiser for donations. We sincerely appreciate the support of our local community for donating to this great cause and ensuring the RSPCA can continue providing care to our wildlife and family pets.<\/p>\n<p>Below, you will find a snippet from the RSPCA\u00a0<em>Imprint<\/em> Magazine (Spring 2013). Please visit the <a title=\"RSPCA Queensland\" href=\"http:\/\/rspcaqld.org.au\" target=\"_blank\">RSPCA website<\/a> for full publications of\u00a0<em>Imprint<\/em> and further information about their organisation.<\/p>\n<div id=\"attachment_1746\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/nextrachermside.com.au\/pages\/content\/uploads\/2013\/10\/2013_rspca_imprint_spring-11.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1746\" class=\"size-full wp-image-1746\" alt=\"RSPCA 'Imprint' Spring 2013\" src=\"http:\/\/nextrachermside.com.au\/pages\/content\/uploads\/2013\/10\/2013_rspca_imprint_spring-11.png\" width=\"300\" height=\"876\" \/><\/a><p id=\"caption-attachment-1746\" class=\"wp-caption-text\">RSPCA &#8216;Imprint&#8217; Spring 2013<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Our store was recently recognised as RSPCA Queensland&#8217;s top fundraiser for donations. We sincerely appreciate the support of our local community for donating to this great cause and ensuring the RSPCA can continue providing care to our wildlife and family pets. Below, you will find a snippet from the RSPCA\u00a0Imprint Magazine (Spring 2013). Please visit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[50,51],"tags":[53,55,52],"class_list":["post-1745","post","type-post","status-publish","format-standard","hentry","category-charity","category-community","tag-charity-2","tag-community-2","tag-rspca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RSPCA &#039;Imprint&#039; Magazine - Nextra Chermside Newsagency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mitch\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/\"},\"author\":{\"name\":\"Mitch\",\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/#\/schema\/person\/d0fb0b0e3cd6e91b90d95e94ea272b28\"},\"headline\":\"RSPCA &#8216;Imprint&#8217; Magazine\",\"datePublished\":\"2013-10-16T07:35:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/\"},\"wordCount\":82,\"image\":{\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/nextrachermside.com.au\/pages\/content\/uploads\/2013\/10\/2013_rspca_imprint_spring-11.png\",\"keywords\":[\"charity\",\"community\",\"rspca\"],\"articleSection\":[\"Charity\",\"Community\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/\",\"url\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/\",\"name\":\"RSPCA 'Imprint' Magazine - Nextra Chermside Newsagency\",\"isPartOf\":{\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/nextrachermside.com.au\/pages\/content\/uploads\/2013\/10\/2013_rspca_imprint_spring-11.png\",\"datePublished\":\"2013-10-16T07:35:26+00:00\",\"author\":{\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/#\/schema\/person\/d0fb0b0e3cd6e91b90d95e94ea272b28\"},\"breadcrumb\":{\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#primaryimage\",\"url\":\"https:\/\/nextrachermside.com.au\/pages\/content\/uploads\/2013\/10\/2013_rspca_imprint_spring-11.png\",\"contentUrl\":\"https:\/\/nextrachermside.com.au\/pages\/content\/uploads\/2013\/10\/2013_rspca_imprint_spring-11.png\",\"width\":300,\"height\":876,\"caption\":\"RSPCA 'Imprint' Spring 2013\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nextrachermside.com.au\/pages\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RSPCA &#8216;Imprint&#8217; Magazine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/#website\",\"url\":\"https:\/\/nextrachermside.com.au\/pages\/\",\"name\":\"Nextra Chermside Newsagency\",\"description\":\"Westfield Chermside, Brisbane, Queensland - Australia&#039;s #1 Newsagent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nextrachermside.com.au\/pages\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/#\/schema\/person\/d0fb0b0e3cd6e91b90d95e94ea272b28\",\"name\":\"Mitch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nextrachermside.com.au\/pages\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6814b77471509d2bbb5422f3f7f3f38ce070d2653d079bd291de9bd94c09c8f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6814b77471509d2bbb5422f3f7f3f38ce070d2653d079bd291de9bd94c09c8f7?s=96&d=mm&r=g\",\"caption\":\"Mitch\"},\"description\":\"Marketing and eBusiness Manager at Nextra Chermside Newsagency Also qualified as a Commissioner for Declarations, web designer, baking enthusiast, part-time photographer, traveller, racing car passenger and technological guru.\",\"sameAs\":[\"http:\/\/nextrachermside.com\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RSPCA 'Imprint' Magazine - Nextra Chermside Newsagency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/","twitter_misc":{"Written by":"Mitch"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#article","isPartOf":{"@id":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/"},"author":{"name":"Mitch","@id":"https:\/\/nextrachermside.com.au\/pages\/#\/schema\/person\/d0fb0b0e3cd6e91b90d95e94ea272b28"},"headline":"RSPCA &#8216;Imprint&#8217; Magazine","datePublished":"2013-10-16T07:35:26+00:00","mainEntityOfPage":{"@id":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/"},"wordCount":82,"image":{"@id":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#primaryimage"},"thumbnailUrl":"http:\/\/nextrachermside.com.au\/pages\/content\/uploads\/2013\/10\/2013_rspca_imprint_spring-11.png","keywords":["charity","community","rspca"],"articleSection":["Charity","Community"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/","url":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/","name":"RSPCA 'Imprint' Magazine - Nextra Chermside Newsagency","isPartOf":{"@id":"https:\/\/nextrachermside.com.au\/pages\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#primaryimage"},"image":{"@id":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#primaryimage"},"thumbnailUrl":"http:\/\/nextrachermside.com.au\/pages\/content\/uploads\/2013\/10\/2013_rspca_imprint_spring-11.png","datePublished":"2013-10-16T07:35:26+00:00","author":{"@id":"https:\/\/nextrachermside.com.au\/pages\/#\/schema\/person\/d0fb0b0e3cd6e91b90d95e94ea272b28"},"breadcrumb":{"@id":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#primaryimage","url":"https:\/\/nextrachermside.com.au\/pages\/content\/uploads\/2013\/10\/2013_rspca_imprint_spring-11.png","contentUrl":"https:\/\/nextrachermside.com.au\/pages\/content\/uploads\/2013\/10\/2013_rspca_imprint_spring-11.png","width":300,"height":876,"caption":"RSPCA 'Imprint' Spring 2013"},{"@type":"BreadcrumbList","@id":"https:\/\/nextrachermside.com.au\/pages\/rspca-imprint-magazine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nextrachermside.com.au\/pages\/"},{"@type":"ListItem","position":2,"name":"RSPCA &#8216;Imprint&#8217; Magazine"}]},{"@type":"WebSite","@id":"https:\/\/nextrachermside.com.au\/pages\/#website","url":"https:\/\/nextrachermside.com.au\/pages\/","name":"Nextra Chermside Newsagency","description":"Westfield Chermside, Brisbane, Queensland - Australia&#039;s #1 Newsagent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nextrachermside.com.au\/pages\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/nextrachermside.com.au\/pages\/#\/schema\/person\/d0fb0b0e3cd6e91b90d95e94ea272b28","name":"Mitch","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nextrachermside.com.au\/pages\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6814b77471509d2bbb5422f3f7f3f38ce070d2653d079bd291de9bd94c09c8f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6814b77471509d2bbb5422f3f7f3f38ce070d2653d079bd291de9bd94c09c8f7?s=96&d=mm&r=g","caption":"Mitch"},"description":"Marketing and eBusiness Manager at Nextra Chermside Newsagency Also qualified as a Commissioner for Declarations, web designer, baking enthusiast, part-time photographer, traveller, racing car passenger and technological guru.","sameAs":["http:\/\/nextrachermside.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/nextrachermside.com.au\/pages\/wp-json\/wp\/v2\/posts\/1745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextrachermside.com.au\/pages\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nextrachermside.com.au\/pages\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nextrachermside.com.au\/pages\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nextrachermside.com.au\/pages\/wp-json\/wp\/v2\/comments?post=1745"}],"version-history":[{"count":1,"href":"https:\/\/nextrachermside.com.au\/pages\/wp-json\/wp\/v2\/posts\/1745\/revisions"}],"predecessor-version":[{"id":1747,"href":"https:\/\/nextrachermside.com.au\/pages\/wp-json\/wp\/v2\/posts\/1745\/revisions\/1747"}],"wp:attachment":[{"href":"https:\/\/nextrachermside.com.au\/pages\/wp-json\/wp\/v2\/media?parent=1745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nextrachermside.com.au\/pages\/wp-json\/wp\/v2\/categories?post=1745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nextrachermside.com.au\/pages\/wp-json\/wp\/v2\/tags?post=1745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}